{"id":16874,"date":"2025-01-31T08:23:07","date_gmt":"2025-01-31T12:23:07","guid":{"rendered":"https:\/\/prensapresidencialvenezuela.gob.ve\/?p=16874"},"modified":"2025-01-31T08:27:34","modified_gmt":"2025-01-31T12:27:34","slug":"inicio-la-operacion-relampago-del-catatumbo-en-la-frontera-con-colombia","status":"publish","type":"post","link":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/2025\/01\/31\/inicio-la-operacion-relampago-del-catatumbo-en-la-frontera-con-colombia\/","title":{"rendered":"Inici\u00f3 la Operaci\u00f3n \u00abRel\u00e1mpago del Catatumbo\u00bb en la frontera con Colombia"},"content":{"rendered":"\n<p><strong>Palacio de Miraflores, Caracas. &#8211;<\/strong> En un anuncio realizado a trav\u00e9s de la red social Telegram, el presidente de la Republica y comandante en jefe de la Fuerza Armada Nacional Bolivariana (FANB), Nicol\u00e1s Maduro, anunci\u00f3 el inicio de la operaci\u00f3n \u00abRel\u00e1mpago del Catatumbo\u00bb, en regiones fronterizas con Colombia.<\/p>\n\n\n\n<p>Esta operaci\u00f3n que forma parte del programa de defensa Escudo Bolivariano 2025, abarcar\u00e1 desde el norte del T\u00e1chira hasta las zonas cercanas al Zulia.<\/p>\n\n\n\n<p>\u00ab(\u2026) en toda la regi\u00f3n fronteriza con nuestra hermana Colombia desde las regiones del norte del T\u00e1chira colindante con norte de Santander hasta las regiones del Zulia de la zona sur, a toda esa zona de r\u00edos cercana al Catatumbo, aqu\u00ed vamos con toda la fuerza militar completa, integral\u00bb, detall\u00f3.<\/p>\n\n\n\n<p>El presidente Maduro destac\u00f3 que esta operaci\u00f3n tiene como objetivo garantizar la seguridad y la paz en el territorio venezolano, as\u00ed como la erradicaci\u00f3n de actividades il\u00edcitas.<\/p>\n\n\n\n<p>\u00abVamos con toda la fuerza militar completa, integral\u00bb, afirm\u00f3 el Mandatario, quien tambi\u00e9n inform\u00f3 que est\u00e1 haciendo coordinaciones con su hom\u00f3logo colombiano Gustavo Petro, para promover un desarrollo binacional que sea econ\u00f3mico y social, con un enfoque humano.<\/p>\n\n\n\n<p>El presidente venezolano explic\u00f3 que estos ejercicios militares se realizan al menos tres veces al a\u00f1o en esta regi\u00f3n, que ha sido hist\u00f3ricamente afectada por conflictos relacionados con el narcotr\u00e1fico.<\/p>\n\n\n\n<p>\u00abHemos logrado liberar y mantener libre todo el territorio de Venezuela de pistas clandestinas, sembrad\u00edos y laboratorios\u00bb, subray\u00f3.<\/p>\n\n\n\n<p>La operaci\u00f3n Rel\u00e1mpago del Catatumbo es en una estrategia amplia de ocupaci\u00f3n territorial y limpieza de elementos perturbadores en la zona.<\/p>\n\n\n\n<p>El Jefe de Estado enfatiz\u00f3 su compromiso con la paz y la integraci\u00f3n entre los pueblos de Colombia y Venezuela, al manifestar: \u00abAmamos la paz y siempre estamos dispuestos a construir los caminos de la integraci\u00f3n y la hermandad\u00bb.<\/p>\n\n\n\n<p>\u00abRel\u00e1mpago del Catatumbo adelante, a la carga, al combate, a la batalla y a la victoria (\u2026) El Estado superior de la Fuerza Armada Nacional Bolivariana desplegado en el territorio, estaremos informando durante todo el d\u00eda y en el desarrollo de toda la operaci\u00f3n Rel\u00e1mpago del Catatumbo\u00bb, destac\u00f3.<\/p>\n\n\n\n<p><strong>Prensa Presidencial \/ Eduardo Hueck<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palacio de Miraflores, Caracas. &#8211; En un anuncio realizado a trav\u00e9s de la red social Telegram, el presidente de la Republica y comandante en jefe de la Fuerza Armada Nacional Bolivariana (FANB), Nicol\u00e1s Maduro, anunci\u00f3 el inicio de la operaci\u00f3n \u00abRel\u00e1mpago del Catatumbo\u00bb, en regiones fronterizas con Colombia. Esta operaci\u00f3n que forma parte del programa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,7],"tags":[65,19,27,20],"class_list":["post-16874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-principales","category-notas-de-prensa","tag-fanb","tag-nicolas-maduro","tag-revolucion-bolivariana","tag-venezuela"],"_links":{"self":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/16874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/comments?post=16874"}],"version-history":[{"count":3,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/16874\/revisions"}],"predecessor-version":[{"id":16879,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/16874\/revisions\/16879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/media\/16875"}],"wp:attachment":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/media?parent=16874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/categories?post=16874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/tags?post=16874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}