{"id":50261,"date":"2026-07-15T16:15:13","date_gmt":"2026-07-15T20:15:13","guid":{"rendered":"https:\/\/prensapresidencialvenezuela.gob.ve\/?p=50261"},"modified":"2026-07-15T16:15:15","modified_gmt":"2026-07-15T20:15:15","slug":"despliegue-del-estado-mayor-garantiza-asistencia-medica-y-servicios-esenciales-a-familias-afectadas","status":"publish","type":"post","link":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/2026\/07\/15\/despliegue-del-estado-mayor-garantiza-asistencia-medica-y-servicios-esenciales-a-familias-afectadas\/","title":{"rendered":"Despliegue del Estado Mayor garantiza asistencia m\u00e9dica y servicios esenciales a familias afectadas"},"content":{"rendered":"\n<p><strong>Caracas, Venezuela. &#8211;<\/strong> \u200bEl presidente de la Asamblea Nacional y del Estado Mayor para la Creaci\u00f3n de Campamentos Transitorios y la Planificaci\u00f3n de Construcci\u00f3n de Viviendas, Jorge Rodr\u00edguez, present\u00f3 el balance de gesti\u00f3n correspondiente a este 15 de julio de 2026 sobre el despliegue operativo en las zonas afectadas por la contingencia.<\/p>\n\n\n\n<p>El reporte oficial registra un total de 128.324 familias atendidas, 106 campamentos transitorios operativos que albergan a 20.857 personas y un registro de 17.907 ciudadanos sin vivienda. En materia log\u00edstica y de salud, se han distribuido 24.232.965 litros de agua potable, 10.063 toneladas de alimentos y se han brindado servicios m\u00e9dicos a 34.872 pacientes en las \u00e1reas abordadas.<\/p>\n\n\n\n<p>\u200bLa ejecuci\u00f3n de estas labores en el terreno cuenta con la participaci\u00f3n de 31.315 voluntarios, 30.989 efectivos institucionales desplegados y el apoyo de 2.408 rescatistas internacionales. El balance de infraestructura mantiene un acumulado de 856 edificios afectados y 190 estructuras colapsadas, en un contexto donde el registro hist\u00f3rico de r\u00e9plicas se ubica en 1.284 eventos. Asimismo, las cifras de afectaci\u00f3n humana consolidan 6.462 personas rescatadas, 16.740 heridos y un total de 4.829 fallecidos asociados a la contingencia s\u00edsmica.<\/p>\n\n\n\n<p><strong>Prensa Presidencial \/ Kaylib Maita<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caracas, Venezuela. &#8211; \u200bEl presidente de la Asamblea Nacional y del Estado Mayor para la Creaci\u00f3n de Campamentos Transitorios y la Planificaci\u00f3n de Construcci\u00f3n de Viviendas, Jorge Rodr\u00edguez, present\u00f3 el balance de gesti\u00f3n correspondiente a este 15 de julio de 2026 sobre el despliegue operativo en las zonas afectadas por la contingencia. El reporte oficial [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":50262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,7],"tags":[2174,1888,20],"class_list":["post-50261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-principales","category-notas-de-prensa","tag-balance-oficial","tag-jorge-rodriguez","tag-venezuela"],"_links":{"self":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/50261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/comments?post=50261"}],"version-history":[{"count":1,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/50261\/revisions"}],"predecessor-version":[{"id":50263,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/50261\/revisions\/50263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/media\/50262"}],"wp:attachment":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/media?parent=50261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/categories?post=50261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/tags?post=50261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}