{"id":8912,"date":"2024-02-15T16:17:37","date_gmt":"2024-02-15T20:17:37","guid":{"rendered":"http:\/\/172.27.0.121\/?p=8912"},"modified":"2024-04-15T16:21:15","modified_gmt":"2024-04-15T20:21:15","slug":"1x10-del-buen-gobierno-debe-alcanzar-95-de-casos-atendidos-al-mes-de-julio","status":"publish","type":"post","link":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/2024\/02\/15\/1x10-del-buen-gobierno-debe-alcanzar-95-de-casos-atendidos-al-mes-de-julio\/","title":{"rendered":"1&#215;10 del Buen Gobierno debe alcanzar 95% de casos atendidos al mes de julio"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>Palacio de Miraflores, Caracas.- <\/strong>Con el prop\u00f3sito de garantizar la atenci\u00f3n integral al pueblo venezolano, este jueves, el presidente de la Rep\u00fablica, Nicol\u00e1s Maduro, hizo un llamado a las autoridades e instituciones del Estado a elevar la eficiencia del sistema 1&#215;10 del Buen Gobierno y del Sistema de Misiones y Grandes Misiones a un 95% en la resoluci\u00f3n de las denuncias del pueblo venezolano<\/p>\n\n\n\n<p>\u201cSubir del 68% de atenci\u00f3n y soluci\u00f3n de los temas reportados por el pueblo a trav\u00e9s de la l\u00ednea 58 (VenApp) a un 95% para el 1\u00b0 de julio, porque vamos por el cumplimento total de los casos\u201d, asever\u00f3 el Mandatario durante la instalaci\u00f3n del Comando Especial Presidencial de Gobierno.<\/p>\n\n\n\n<p>En este sentido, el Mandatario design\u00f3 al diputado Leonardo Montesuma, como jefe nacional del equipo del Puesto de Comando Presidencial del 1&#215;10 del Buen Gobierno, a quien pidi\u00f3 vincular los programas sociales, misiones y grandes misiones, \u201cpara garantizar soluciones al pueblo venezolano\u201d.<\/p>\n\n\n\n<p>\u201cSe trata de avanzar con mucha voluntad y decisi\u00f3n en un proceso de concentraci\u00f3n de esfuerzos, en un proceso de articulaci\u00f3n de fuerzas para lograr un nivel m\u00e1s elevado de eficiencia en las pol\u00edticas p\u00fablicas en los planes y lograr un 2024 de atenci\u00f3n, soluci\u00f3n de los problemas\u201d, expres\u00f3 el Dignatario.<\/p>\n\n\n\n<p>En este contexto, precis\u00f3 que este Comando debe trabajar y desarrollar planes que vinculen tres componentes vitales, a saber: 1. 1X10 del Buen Gobierno; 2. Las Brigadas Comunitarias Militares para la Educaci\u00f3n y la Salud (Bricomiles); 3. Misiones y grandes misiones sociales.<\/p>\n\n\n\n<p>Asimismo, exhort\u00f3 a la Fuerza Armada Nacional Bolivariana (FANB) \u201ca conectarse\u201d en cada estado del pa\u00eds en perfecta uni\u00f3n c\u00edvico-militar \u201cpara trabajar, arreglar cosas, mejorar y prosperar en una nueva etapa de construcci\u00f3n del bienestar social del pueblo.<\/p>\n\n\n\n<p>De igual manera, hizo un llamado a los hombres y mujeres a mantenerse en combate permanente contra el burocratismo que busca acabar con los programas sociales que impulsar el Gobierno Bolivariano.<\/p>\n\n\n\n<p>\u201cDebemos crear las condiciones \u00f3ptimas para el despliegue de los planes de los nuevos m\u00e9todos de trabajo, crear las condiciones, por eso se est\u00e1 conformando este Comando Especial Presidencial de Gobierno\u201d.<\/p>\n\n\n\n<p>Prensa Presidencial\/Joelin Jim\u00e9nez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palacio de Miraflores, Caracas.- Con el prop\u00f3sito de garantizar la atenci\u00f3n integral al pueblo venezolano, este jueves, el presidente de la Rep\u00fablica, Nicol\u00e1s Maduro, hizo un llamado a las autoridades e instituciones del Estado a elevar la eficiencia del sistema 1&#215;10 del Buen Gobierno y del Sistema de Misiones y Grandes Misiones a un 95% [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-8912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa"],"_links":{"self":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/8912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/comments?post=8912"}],"version-history":[{"count":1,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/8912\/revisions"}],"predecessor-version":[{"id":8917,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/8912\/revisions\/8917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/media\/8916"}],"wp:attachment":[{"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/media?parent=8912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/categories?post=8912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/wp-json\/wp\/v2\/tags?post=8912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}